{"id":23701,"date":"2022-12-05T08:38:26","date_gmt":"2022-12-05T08:38:26","guid":{"rendered":"https:\/\/dev-carpetsafari.digitalengage.biz\/%d8%b1%d9%86%da%af\/"},"modified":"2023-05-15T14:55:22","modified_gmt":"2023-05-15T14:55:22","slug":"%d8%b1%d9%86%da%af","status":"publish","type":"page","link":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/%d8%b1%d9%86%da%af\/","title":{"rendered":"\u0631\u0646\u06af"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23701\" class=\"elementor elementor-23701 elementor-23062\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c839890 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"c839890\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0aa69f\" data-id=\"f0aa69f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19caf5f elementor-widget elementor-widget-heading\" data-id=\"19caf5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.5 - 27-04-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-large\">\u062e\u0631\u06cc\u062f \u0628\u0631 \u0627\u0633\u0627\u0633 \u0631\u0646\u06af<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a3f3e9 elementor-widget elementor-widget-spacer\" data-id=\"3a3f3e9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.5 - 27-04-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5636b elementor-widget elementor-widget-html\" data-id=\"ec5636b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"color_image\"><li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0642\u0631\u0645\u0632\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Red-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0637\u0644\u0627\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Gold-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0646\u0627\u0631\u0646\u062c\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Orange-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0632\u0631\u062f\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Yellow-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0633\u0641\u06cc\u062f-\u062e\u0627\u0645\u0648\u0634\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Off-White-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0645\u0627\u0631\u0648\u0646\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Maroon-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0633\u0628\u0632\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Green-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0628\u0648\u0631\u06af\u0648\u0646\u062f\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Burgundy-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0631\u0646\u06af-\u0628\u0698\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Beige-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0631\u0646\u06af-\u0635\u0648\u0631\u062a\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Pink-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0645\u0634\u06a9\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Black-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0622\u0628\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Blue-Color.png\"><\/a><\/li>\n<li><a href=\"\/fa\/\u062e\u0631\u06cc\u062f-\u06a9\u0646\u06cc\u062f\/?yith_wcan=1&filter_prominent-color=\u0631\u0646\u06af-\u0642\u0647\u0648\u0647-\u0627\u06cc\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/02\/Brown-Color.png\"><\/a><\/li>\n<\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c2b06 elementor-widget elementor-widget-spacer\" data-id=\"d7c2b06\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u062e\u0631\u06cc\u062f \u0628\u0631 \u0627\u0633\u0627\u0633 \u0631\u0646\u06af<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23701","page","type-page","status-publish","hentry","post-no-thumbnail"],"_links":{"self":[{"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/pages\/23701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/comments?post=23701"}],"version-history":[{"count":29,"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/pages\/23701\/revisions"}],"predecessor-version":[{"id":26080,"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/pages\/23701\/revisions\/26080"}],"wp:attachment":[{"href":"https:\/\/dev-carpetsafari.digitalengage.biz\/fa\/wp-json\/wp\/v2\/media?parent=23701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}